{"id":2663,"date":"2026-02-06T12:35:54","date_gmt":"2026-02-06T11:35:54","guid":{"rendered":"https:\/\/theplacetobemagazine.com\/?p=2663"},"modified":"2026-02-06T12:39:39","modified_gmt":"2026-02-06T11:39:39","slug":"micam-101","status":"publish","type":"post","link":"https:\/\/theplacetobemagazine.com\/index.php\/2026\/02\/06\/micam-101\/","title":{"rendered":"MICAM 101"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2663\" class=\"elementor elementor-2663\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6d2f89fe e-con-full e-flex e-con e-parent\" data-id=\"6d2f89fe\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d4b466f elementor-nav-menu__align-center elementor-widget__width-inherit elementor-nav-menu--stretch elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-global elementor-global-1690 elementor-widget-nav-menu\" data-id=\"d4b466f\" data-element_type=\"widget\" data-settings=\"{&quot;full_width&quot;:&quot;stretch&quot;,&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;fas fa-caret-down&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/theplacetobemagazine.com\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-nav-menu.min.css\">\t\t\t<nav class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-background e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-d4b466f\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-53\"><a href=\"https:\/\/theplacetobemagazine.com\/\" class=\"elementor-item\">Home<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-285\"><a href=\"https:\/\/theplacetobemagazine.com\/index.php\/partner\/\" class=\"elementor-item\">Partner<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-284\"><a href=\"https:\/\/theplacetobemagazine.com\/index.php\/servizi\/\" class=\"elementor-sub-item\">Servizi<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-282\"><a href=\"https:\/\/theplacetobemagazine.com\/index.php\/horeca\/\" class=\"elementor-sub-item\">Horeca<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-283\"><a href=\"https:\/\/theplacetobemagazine.com\/index.php\/made-in-italy\/\" class=\"elementor-sub-item\">Made in italy<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1046\"><a href=\"https:\/\/theplacetobemagazine.com\/index.php\/pubblicazioni\/\" class=\"elementor-item\">Pubblicazioni<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-993\"><a href=\"https:\/\/theplacetobemagazine.com\/index.php\/media-kit\/\" class=\"elementor-item\">Media Kit<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-994\"><a href=\"https:\/\/theplacetobemagazine.com\/index.php\/chi-siamo\/\" class=\"elementor-item\">Chi siamo<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu di commutazione\" aria-expanded=\"false\">\n\t\t\t<svg aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open e-font-icon-svg e-eicon-menu-bar\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M104 333H896C929 333 958 304 958 271S929 208 896 208H104C71 208 42 237 42 271S71 333 104 333ZM104 583H896C929 583 958 554 958 521S929 458 896 458H104C71 458 42 487 42 521S71 583 104 583ZM104 833H896C929 833 958 804 958 771S929 708 896 708H104C71 708 42 737 42 771S71 833 104 833Z\"><\/path><\/svg><svg aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close e-font-icon-svg e-eicon-close\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M742 167L500 408 258 167C246 154 233 150 217 150 196 150 179 158 167 167 154 179 150 196 150 212 150 229 154 242 171 254L408 500 167 742C138 771 138 800 167 829 196 858 225 858 254 829L496 587 738 829C750 842 767 846 783 846 800 846 817 842 829 829 842 817 846 804 846 783 846 767 842 750 829 737L588 500 833 258C863 229 863 200 833 171 804 137 775 137 742 167Z\"><\/path><\/svg>\t\t\t<span class=\"elementor-screen-only\">Menu<\/span>\n\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-d4b466f\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-53\"><a href=\"https:\/\/theplacetobemagazine.com\/\" class=\"elementor-item\" tabindex=\"-1\">Home<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-285\"><a href=\"https:\/\/theplacetobemagazine.com\/index.php\/partner\/\" class=\"elementor-item\" tabindex=\"-1\">Partner<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-284\"><a href=\"https:\/\/theplacetobemagazine.com\/index.php\/servizi\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Servizi<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-282\"><a href=\"https:\/\/theplacetobemagazine.com\/index.php\/horeca\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Horeca<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-283\"><a href=\"https:\/\/theplacetobemagazine.com\/index.php\/made-in-italy\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Made in italy<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1046\"><a href=\"https:\/\/theplacetobemagazine.com\/index.php\/pubblicazioni\/\" class=\"elementor-item\" tabindex=\"-1\">Pubblicazioni<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-993\"><a href=\"https:\/\/theplacetobemagazine.com\/index.php\/media-kit\/\" class=\"elementor-item\" tabindex=\"-1\">Media Kit<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-994\"><a href=\"https:\/\/theplacetobemagazine.com\/index.php\/chi-siamo\/\" class=\"elementor-item\" tabindex=\"-1\">Chi siamo<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58c55b2f elementor-widget elementor-widget-image\" data-id=\"58c55b2f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"189\" src=\"https:\/\/theplacetobemagazine.com\/wp-content\/uploads\/2024\/04\/LogoTPTBBianco.png\" class=\"attachment-large size-large wp-image-64\" alt=\"\" srcset=\"https:\/\/theplacetobemagazine.com\/wp-content\/uploads\/2024\/04\/LogoTPTBBianco.png 973w, https:\/\/theplacetobemagazine.com\/wp-content\/uploads\/2024\/04\/LogoTPTBBianco-300x71.png 300w, https:\/\/theplacetobemagazine.com\/wp-content\/uploads\/2024\/04\/LogoTPTBBianco-768x182.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-638192ed elementor-widget elementor-widget-heading\" data-id=\"638192ed\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">MICAM 101<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e337925 e-flex e-con-boxed e-con e-parent\" data-id=\"e337925\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5830853 elementor-widget elementor-widget-text-editor\" data-id=\"5830853\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Subito dopo le Olimpiadi si apre MICAM, l\u2019evento leader globale dedicato alla calzatura, in<br \/>programma a Fiera Milano Rho dal 22 al 24 febbraio 2026.<br \/>In realt\u00e0 le Olimpiadi finiscono il 22, ma l\u2019epicentro si sposta a Verona dove faranno l\u2019evento<br \/>conclusivo. Quindi le Olimpiadi lasciano l\u2019incognito della questione della presenza al Micam.<br \/>Verr\u00e0 pi\u00f9 gente attirata dagli ultimi giorni delle Olimpiadi, o viceversa si spaventeranno dalla troppa<br \/>gente e dai prezzi folli di alloggi? Vedremo.<br \/>Nel frattempo, la fiera propone un nuovo layout pi\u00f9 fluido e leggibile. MICAM si rinnova attraverso<br \/>un approccio olistico che abbraccia tutte le dimensioni del prodotto calzatura, integrando<br \/>produzione, design e innovazione in un racconto unitario. Un percorso costruito sull\u2019ascolto e sulla<br \/>visione, che valorizza il Made in Italy e, al tempo stesso, l\u2019eccellenza internazionale che anima il<br \/>settore.<br \/>MICAM introduce una nuova distribuzione dei Padiglioni puntando sul prodotto. Il padiglione 1<br \/>ospiter\u00e0 le calzature che vanno dall\u2019eleganza delle occasioni importanti al comfort della<br \/>quotidianit\u00e0; il padiglione 3 metter\u00e0 in mostra stile e creativit\u00e0 per calzature che sanno andare<br \/>oltre il formale; al padiglione 2 e 4 innovazione e contemporaneit\u00e0 per calzature che raccontano<br \/>l\u2019evoluzione della moda e del gusto; al padiglione 5 calzature che riflettono gli stili e le tendenze<br \/>globali.<br \/>Le aree istituzionali di MICAM come la VIP Buyers Lounge, il Ristorante e l&amp;#39;Ufficio Stampa saranno<br \/>collocate in fondo al Padiglione 1, mentre MICAM Next con i seminari curati da WIRED Italia,<br \/>l\u2019area Trends &amp;amp; Materials, le presentazioni delle tendenze e della Buyer\u2019s Guide, sar\u00e0 posizionato<br \/>in fondo al Padiglione 3 insieme all&amp;#39;area Emerging Designer e Future of Retail, creando un polo<br \/>dedicato all&amp;#39;innovazione e alle nuove tendenze del settore.<br \/>Al centro del Padiglione 5 prender\u00e0 forma M&amp;amp;M \u2013 The Hub, un nuovo spazio pensato per<br \/>accogliere iniziative e progetti sviluppati in piena sinergia tra MICAM e MIPEL. All\u2019interno dell\u2019Hub,<br \/>MICAM Academy e MIPEL Factory saranno riunite in un\u2019unica anima che combina formazione,<br \/>ricerca, sperimentazione tecnica e approfondimento professionale.<br \/>Si trasferir\u00e0 nell\u2019Hub anche l\u2019area Italian Startup, il progetto realizzato in collaborazione con ICE-<br \/>Agenzia e il Ministero degli Affari Esteri e della Cooperazione Internazionale (MAECI), dedicato a<br \/>una selezione di aziende italiane emergenti. Completeranno l\u2019esperienza uno spazio dedicato al<br \/>prodotto, con una esposizione di modelli di calzature e borse interpretati secondo tre macro-trend<br \/>della stagione Autunno\/Inverno 2026\u20132027, e un\u2019area relax, pensata per offrire ai visitatori<br \/>momenti di pausa in un ambiente confortevole.<br \/>Giovanna Ceolini, Presidente MICAM: &amp;quot;L\u2019edizione invernale di febbraio di MICAM nasce con<br \/>l\u2019obiettivo di valorizzare la filiera calzaturiera, restituire un\u2019immagine contemporanea del settore e<br \/>offrire un\u2019esperienza immersiva in cui business, intrattenimento, formazione e innovazione si<br \/>intrecciano in un percorso progettuale pensato su misura per buyer ed espositori. Abbiamo avviato<br \/>una revisione complessiva che partir\u00e0 da febbraio e proseguir\u00e0 nelle edizioni successive, per<br \/>rendere la visita sempre pi\u00f9 semplice e immediata e permettere ai buyer di riconoscere con<br \/>chiarezza la merceologia presente in ogni padiglione.\u201d<br \/>Evgeny Utkin<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67fbfb2 elementor-widget elementor-widget-image\" data-id=\"67fbfb2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"452\" src=\"https:\/\/theplacetobemagazine.com\/wp-content\/uploads\/2026\/02\/Image-1-1024x578.jpg\" class=\"attachment-large size-large wp-image-2665\" alt=\"\" srcset=\"https:\/\/theplacetobemagazine.com\/wp-content\/uploads\/2026\/02\/Image-1-1024x578.jpg 1024w, https:\/\/theplacetobemagazine.com\/wp-content\/uploads\/2026\/02\/Image-1-300x169.jpg 300w, https:\/\/theplacetobemagazine.com\/wp-content\/uploads\/2026\/02\/Image-1-768x433.jpg 768w, https:\/\/theplacetobemagazine.com\/wp-content\/uploads\/2026\/02\/Image-1.jpg 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Subito dopo le Olimpiadi si apre MICAM, l\u2019evento leader globale dedicato alla calzatura, inprogramma a Fiera Milano Rho dal 22 al 24 febbraio 2026.In realt\u00e0 le Olimpiadi finiscono il 22, ma l\u2019epicentro si sposta a Verona dove faranno l\u2019eventoconclusivo. Quindi le Olimpiadi lasciano l\u2019incognito della questione della presenza al Micam.Verr\u00e0 pi\u00f9 gente attirata dagli ultimi [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2666,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-2663","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articoi"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/theplacetobemagazine.com\/index.php\/wp-json\/wp\/v2\/posts\/2663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theplacetobemagazine.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theplacetobemagazine.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theplacetobemagazine.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/theplacetobemagazine.com\/index.php\/wp-json\/wp\/v2\/comments?post=2663"}],"version-history":[{"count":4,"href":"https:\/\/theplacetobemagazine.com\/index.php\/wp-json\/wp\/v2\/posts\/2663\/revisions"}],"predecessor-version":[{"id":2669,"href":"https:\/\/theplacetobemagazine.com\/index.php\/wp-json\/wp\/v2\/posts\/2663\/revisions\/2669"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theplacetobemagazine.com\/index.php\/wp-json\/wp\/v2\/media\/2666"}],"wp:attachment":[{"href":"https:\/\/theplacetobemagazine.com\/index.php\/wp-json\/wp\/v2\/media?parent=2663"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theplacetobemagazine.com\/index.php\/wp-json\/wp\/v2\/categories?post=2663"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theplacetobemagazine.com\/index.php\/wp-json\/wp\/v2\/tags?post=2663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}